{"id":1772,"date":"2025-06-05T11:02:50","date_gmt":"2025-06-05T03:02:50","guid":{"rendered":"https:\/\/www.zleygroup.com\/?page_id=1772"},"modified":"2026-03-03T15:58:39","modified_gmt":"2026-03-03T07:58:39","slug":"formulazione","status":"publish","type":"page","link":"https:\/\/www.zleygroup.com\/it\/formulation\/","title":{"rendered":"FORMULAZIONE"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1772\" class=\"elementor elementor-1772\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6622e37 e-flex e-con-boxed e-con e-parent\" data-id=\"6622e37\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48c17ea elementor-widget elementor-widget-breadcrumbs\" data-id=\"48c17ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav aria-label=\"pangrattato\" class=\"rank-math-breadcrumb\"><p><span class=\"last\">Casa<\/span><\/p><\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b329fcd e-flex e-con-boxed e-con e-parent\" data-id=\"b329fcd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c301f2 elementor-widget elementor-widget-heading\" data-id=\"4c301f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">formulazione cosmetica di prodotti per la cura della pelle<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9c8302 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"c9c8302\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le nostre formule non solo riflettono le ultime tendenze del trattamento della pelle, ma bilanciano anche stabilit\u00e0 e valore pratico di applicazione. Dal classico retinolo tradizionale all'ingrediente alternativo delicato bakuchiol, fino all'acido ferulico antiossidante, ogni soluzione si basa su ingredienti funzionali per aiutarvi a sviluppare prodotti finali sempre pi\u00f9 all'avanguardia sul mercato.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-598deda elementor-widget elementor-widget-html\" data-id=\"598deda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"zley-filter\">\r\n  <button class=\"zbtn is-active\" data-filter=\"all\">- TUTTI<\/button>\r\n  <button class=\"zbtn\" data-filter=\"well-aging\">- BENESSERE<\/button>\r\n  <button class=\"zbtn\" data-filter=\"repairing\">- RIPARAZIONE<\/button>\r\n  <button class=\"zbtn\" data-filter=\"brightening\">- L'ILLUMINAZIONE<\/button>\r\n  <button class=\"zbtn\" data-filter=\"soothing\">- LENITIVO<\/button>\r\n  <button class=\"zbtn\" data-filter=\"eyecare\">- OCCHIO<\/button>\r\n  <button class=\"zbtn\" data-filter=\"acne\">- ACNE<\/button>\r\n  <button class=\"zbtn\" data-filter=\"scalpcare\">- SCALPCARE<\/button>\r\n  <button class=\"zbtn\" data-filter=\"toiletery\">- TOILETTERIA<\/button>\r\n<\/div>\r\n\r\n<script>\r\ndocument.addEventListener('DOMContentLoaded', function(){\r\n  const btns = document.querySelectorAll('.zley-filter .zbtn');\r\n  const cards = document.querySelectorAll('.pdf-box');\r\n\r\n  function applyFilter(key){\r\n    cards.forEach(card=>{\r\n      const cats = (card.getAttribute('data-cat')||'').split(',').map(s=>s.trim());\r\n      const show = (key==='all') || cats.includes(key);\r\n      card.style.display = show ? '' : 'none';\r\n    });\r\n  }\r\n\r\n  btns.forEach(btn=>{\r\n    btn.addEventListener('click', ()=>{\r\n      btns.forEach(b=>b.classList.remove('is-active'));\r\n      btn.classList.add('is-active');\r\n      applyFilter(btn.dataset.filter);\r\n    });\r\n  });\r\n\r\n  applyFilter('all'); \/\/ \u9ed8\u8ba4\u663e\u793a\u5168\u90e8\r\n});\r\n<\/script>\r\n\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-677e292 e-con-full e-flex e-con e-parent\" data-id=\"677e292\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-91d0034 elementor-widget elementor-widget-html\" data-id=\"91d0034\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\r\n\/* === \u4e24\u5217\u5e03\u5c40 + \u6bcf\u4e2a\u6587\u4ef6\u72ec\u7acb\u767d\u8272\u8fb9\u6846 === *\/\r\n.pdf-list{\r\n  display:grid;\r\n  grid-template-columns:1fr 1fr; \/* \u4e24\u5217 *\/\r\n  gap:0;                         \/* \u8fb9\u6846\u81ea\u5df1\u753b\u5206\u9694\uff0c\u4e0d\u8981\u95f4\u8ddd *\/\r\n}\r\n\r\n.pdf-box{\r\n  display:grid;\r\n  grid-template-columns:88px 1fr; \/* \u5de6\u56fe\u6807 + \u53f3\u5185\u5bb9 *\/\r\n  gap:18px;\r\n  align-items:start;\r\n  padding:20px;\r\n  background:transparent;\r\n  box-sizing:border-box;\r\n  border:1px solid #fff;          \/* \u6bcf\u4e2a\u683c\u5b50\u4e00\u5708\u767d\u8fb9\u6846 *\/\r\n}\r\n\r\n\/* code \u6807\u7b7e\uff1a\u6df1\u7d2b\u5e95\u767d\u5b57 + \u53f3\u4fa7\u7bad\u5934 *\/\r\n.pdf-code{\r\n  display:flex;                \/* \u6539\u6210 flex \u5e03\u5c40 *\/\r\n  align-items:center;          \/* \u5782\u76f4\u5c45\u4e2d *\/\r\n  justify-content:space-between; \/* \u5de6\u8fb9\u7f16\u53f7\uff0c\u53f3\u8fb9\u7bad\u5934 *\/\r\n  background:#3A1C54;\r\n  width:100%;\r\n  color:#fff;\r\n  font-weight:500;\r\n  font-size:14px;\r\n  padding:4px 10px;\r\n  border-radius:6px;\r\n  margin:6px 0 10px;\r\n  box-sizing:border-box;\r\n}\r\n\r\n.pdf-code::after{\r\n  content:\"\\25BC\";             \/* \u25bc \u5411\u4e0b\u7bad\u5934 *\/\r\n  font-size:12px;\r\n  color:#fff;\r\n  margin-left:8px;             \/* \u7f16\u53f7\u548c\u7bad\u5934\u4e4b\u95f4\u7559\u70b9\u7a7a\u9699 *\/\r\n}\r\n\r\n\r\n\/* \u4f60\u539f\u6765\u7684 PDF \u56fe\u6807\/\u4e0b\u8f7d\u7684\u57fa\u7840\u6837\u5f0f\uff08\u4fdd\u7559\u539f\u98ce\u683c\uff0c\u53ef\u6309\u9700\u5220\u6539\uff09 *\/\r\n.pdf-icon-wrapper{ display:flex; flex-direction:column; align-items:center; }\r\n.pdf-icon{ position:relative; width:60px; height:80px; background:#fff; border:1px solid #ccc; border-radius:6px; overflow:hidden; display:block; }\r\n.pdf-icon .bar{ position:absolute; left:0; right:0; bottom:0; height:22px; display:flex; align-items:center; justify-content:center; background:#3A1C54; }\r\n.pdf-icon .bar span{ color:#fff; font-weight:800; font-size:10px; letter-spacing:.3px; }\r\n.download-button{\r\n  display:inline-flex;\r\n  align-items:center;\r\n  white-space:nowrap;\r\n  margin-top:8px;\r\n  background:#3A1C54;\r\n  color:#fff !important;\r\n  font-weight:100;\r\n  text-decoration:none;\r\n  font-size:6px;        \/* \u5b57\u4f53\u66f4\u5c0f *\/\r\n  padding:4px 8px;       \/* \u7f29\u5c0f\u4e0a\u4e0b\u5de6\u53f3 padding *\/\r\n  border-radius:4px;\r\n  line-height:1;\r\n  transition:.25s;\r\n}\r\n\r\n.download-button::before{\r\n  content:\"\\2193\";       \/* \u2193 *\/\r\n  margin-right:2px;      \/* \u7bad\u5934\u548c\u7ad6\u7ebf\u7684\u5916\u95f4\u8ddd\u7f29\u5c0f *\/\r\n  padding-right:4px;     \/* \u7ad6\u7ebf\u5185\u95f4\u8ddd\u7f29\u5c0f *\/\r\n  border-right:1px solid #fff;  \/* \u7ad6\u7ebf\u66f4\u7ec6 *\/\r\n  font-size:12px;        \/* \u7bad\u5934\u8ddf\u6587\u5b57\u4e00\u6837\u5c0f *\/\r\n}\r\n\r\n.download-button:hover{\r\n  background:#56276d;\r\n  box-shadow:0 2px 4px rgba(0,0,0,.2);\r\n}\r\n\r\n\r\n\r\n.pdf-title{ font-size:18px; font-weight:800; color:#2C2A35; margin:0; }\r\n.pdf-description{ color:#6B677A; line-height:1.65; margin:0; }\r\n\r\n\/* \u54cd\u5e94\u5f0f\uff1a\u5c0f\u5c4f\u4e00\u5217\uff0c\u4ec5\u663e\u793a\u6a2a\u7ebf\u5373\u53ef *\/\r\n@media (max-width:1024px){\r\n  .pdf-list{ grid-template-columns:1fr; border-left:none; }\r\n  .pdf-box{ border-right:none; }\r\n  .pdf-box:last-child{ border-bottom:none; }\r\n}\r\n<\/style>\r\n\r\n<div class=\"pdf-list\">\r\n\r\n  <!-- WELL-AGING -->\r\n  <div class=\"pdf-box\" data-cat=\"well-aging\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/33D-Ferula-Crystal-Whitening-Cream-L-25041302-1.pdf\" target=\"_blank\" download class=\"pdf-icon\"><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/33D-Ferula-Crystal-Whitening-Cream-L-25041302-1.pdf\" target=\"_blank\" download class=\"download-button\">SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">3 Crema sbiancante ai cristalli di asafoetida<\/div>\r\n      <div class=\"pdf-code\">L-25041302<\/div>\r\n      <div class=\"pdf-description\">Una crema illuminante con cristalli di asafoetida che aiuta a uniformare il tono della pelle, a ridurre le macchie scure e a promuovere un colorito luminoso.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <div class=\"pdf-box\" data-cat=\"well-aging\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Large-brown-can-sealing-film-can-L-24090402-1.pdf\" target=\"_blank\" download class=\"pdf-icon\"><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Large-brown-can-sealing-film-can-L-24090402-1.pdf\" target=\"_blank\" download class=\"download-button\">SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Lattina grande marrone con pellicola sigillante<\/div>\r\n      <div class=\"pdf-code\">L-24090402<\/div>\r\n      <div class=\"pdf-description\">Un film sigillante resistente progettato per contenitori marroni di grandi dimensioni. Garantisce una protezione sicura, igienica ed ermetica dell'imballaggio.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <!-- REPAIRING -->\r\n  <div class=\"pdf-box\" data-cat=\"repairing\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Anti-allergy-lotion-L-24122502-1.pdf\" target=\"_blank\" download class=\"pdf-icon\"><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Anti-allergy-lotion-L-24122502-1.pdf\" target=\"_blank\" download class=\"download-button\">SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Emulsione antiallergica<\/div>\r\n      <div class=\"pdf-code\">L-24122502<\/div>\r\n      <div class=\"pdf-description\">Lenisce e protegge la pelle sensibile con sostanze botaniche calmanti e lipidi che rafforzano la barriera; riduce gli arrossamenti e il disagio.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n\r\n\r\n  <!-- BRIGHTENING -->\r\n  <div class=\"pdf-box\" data-cat=\"brightening\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Korean-water-light-maskL-24090503A-1.pdf\" target=\"_blank\" download class=\"pdf-icon\"><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Korean-water-light-maskL-24090503A-1.pdf\" target=\"_blank\" download class=\"download-button\">SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Maschera coreana all'acqua per il bagliore<\/div>\r\n      <div class=\"pdf-code\">L-24090503A<\/div>\r\n      <div class=\"pdf-description\">Idratazione istantanea grazie all'HA e alle sostanze botaniche; la pelle appare luminosa, rimpolpata e radiosa dopo ogni trattamento di 15 minuti.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <div class=\"pdf-box\" data-cat=\"brightening\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Anti-aging-Cooling-CreamL-24091001-1.pdf\" target=\"_blank\" download class=\"pdf-icon\"><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Anti-aging-Cooling-CreamL-24091001-1.pdf\" target=\"_blank\" download class=\"download-button\">SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Crema rinfrescante anti-et\u00e0<\/div>\r\n      <div class=\"pdf-code\">L-24091001<\/div>\r\n      <div class=\"pdf-description\">Idratazione rinfrescante e principi attivi rassodanti per lenire i rossori, ridurre le linee sottili e ringiovanire la pelle affaticata.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <!-- SOOTHING -->\r\n  <div class=\"pdf-box\" data-cat=\"soothing\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Azulene-Light-Repair-Cream-L-25011503A-1.pdf\" target=\"_blank\" download class=\"pdf-icon\"><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Azulene-Light-Repair-Cream-L-25011503A-1.pdf\" target=\"_blank\" download class=\"download-button\">SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Crema leggera riparatrice Azulene<\/div>\r\n      <div class=\"pdf-code\">L-25011503A<\/div>\r\n      <div class=\"pdf-description\">L'azulene lenitivo e le ceramidi calmano le irritazioni, favoriscono la riparazione della barriera e forniscono un'idratazione leggera.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <div class=\"pdf-box\" data-cat=\"soothing\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Smoothie-Moisturizing-Essence-Cream-L-24070402-1.pdf\" target=\"_blank\" download class=\"pdf-icon\"><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Smoothie-Moisturizing-Essence-Cream-L-24070402-1.pdf\" target=\"_blank\" download class=\"download-button\">SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Crema d'essenza idratante Smoothie<\/div>\r\n      <div class=\"pdf-code\">L-24070402<\/div>\r\n      <div class=\"pdf-description\">Umettanti ultra-idratanti + emollienti dissetano la pelle secca per una finitura liscia, elastica e luminosa che dura nel tempo.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <!-- EYECARE -->\r\n  <div class=\"pdf-box\" data-cat=\"eyecare\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Radiance-Revitalizing-Eye-Oil-L-24111802-1.pdf\" target=\"_blank\" download class=\"pdf-icon\"><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Radiance-Revitalizing-Eye-Oil-L-24111802-1.pdf\" target=\"_blank\" download class=\"download-button\">SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Olio di essenza per gli occhi illuminante<\/div>\r\n      <div class=\"pdf-code\">L-24111802<\/div>\r\n      <div class=\"pdf-description\">Gli antiossidanti e i riflettori della luce attenuano le occhiaie, idratano le linee sottili e rinfrescano il contorno occhi.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <div class=\"pdf-box\" data-cat=\"eyecare\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Eye-Micro-condensed-Purple-Essence-L-24111803A-1.pdf\" target=\"_blank\" download class=\"pdf-icon\"><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Eye-Micro-condensed-Purple-Essence-L-24111803A-1.pdf\" target=\"_blank\" download class=\"download-button\">SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Essenza viola microcondensata per gli occhi<\/div>\r\n      <div class=\"pdf-code\">L-24111803A<\/div>\r\n      <div class=\"pdf-description\">Le sostanze botaniche viola micro-incapsulate nutrono, dissetano e rassodano per un aspetto pi\u00f9 luminoso e rivitalizzato.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n\r\n\r\n  <div class=\"pdf-box\" data-cat=\"acne\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Quick-acting-acne-lightening-creamL-24053103-1.pdf\" target=\"_blank\" download class=\"pdf-icon\"><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Quick-acting-acne-lightening-creamL-24053103-1.pdf\" target=\"_blank\" download class=\"download-button\">SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Crema per la rimozione dell'acne ad azione rapida<\/div>\r\n      <div class=\"pdf-code\">L-24053103<\/div>\r\n      <div class=\"pdf-description\">L'acido salicilico e le sostanze botaniche lenitive eliminano rapidamente le imperfezioni, attenuano i segni e restituiscono una pelle liscia.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <!-- SCALPCARE -->\r\n  <div class=\"pdf-box\" data-cat=\"scalpcare\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Oil-control-anti-oxidation-bottle-L-25030401-1.pdf\" target=\"_blank\" download class=\"pdf-icon\"><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Oil-control-anti-oxidation-bottle-L-25030401-1.pdf\" target=\"_blank\" download class=\"download-button\">SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Bottiglia per il controllo dell'olio e la protezione dall'ossigeno<\/div>\r\n      <div class=\"pdf-code\">L-25030401<\/div>\r\n      <div class=\"pdf-description\">Agisce sulla regolazione del sebo e sulla difesa antiossidante; opacizza proteggendo dagli stress ambientali.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <div class=\"pdf-box\" data-cat=\"scalpcare\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Scalp-Soothing-Toner-Cooling-Feeling-L-25022603B-1.pdf\" target=\"_blank\" download class=\"pdf-icon\"><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Scalp-Soothing-Toner-Cooling-Feeling-L-25022603B-1.pdf\" target=\"_blank\" download class=\"download-button\">SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Lozione lenitiva per il cuoio capelluto (sensazione di raffreddamento)<\/div>\r\n      <div class=\"pdf-code\">L-25022603B<\/div>\r\n      <div class=\"pdf-description\">Sollievo immediato per il cuoio capelluto irritato e pruriginoso; le sostanze botaniche e gli idratanti calmano e ripristinano l'equilibrio dell'idratazione.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <!-- TOILETERY -->\r\n  <div class=\"pdf-box\" data-cat=\"toiletery\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Kiwi-brushed-scrub-cleaning-L-24121002-1.pdf\" target=\"_blank\" download class=\"pdf-icon\"><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Kiwi-brushed-scrub-cleaning-L-24121002-1.pdf\" target=\"_blank\" download class=\"download-button\">SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Pulizia smerigliata spazzolata Kiwi<\/div>\r\n      <div class=\"pdf-code\">L-24121002<\/div>\r\n      <div class=\"pdf-description\">Lo scrub rinfrescante al kiwi esfolia delicatamente e deterge in profondit\u00e0; la pelle \u00e8 liscia e rivitalizzata.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <div class=\"pdf-box\" data-cat=\"toiletery\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/\u4f60\u7684\u57df\u540d\/wp-content\/uploads\/\u8def\u5f84\/toiletery.pdf\" target=\"_blank\" class=\"pdf-icon\" download rel=\"nofollow\"><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/\u4f60\u7684\u57df\u540d\/wp-content\/uploads\/\u8def\u5f84\/toiletery.pdf\" target=\"_blank\" class=\"download-button\" download rel=\"nofollow\">SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Mousse detergente 4 in 1 agli aminoacidi<\/div>\r\n      <div class=\"pdf-code\">L-24060701<\/div>\r\n      <div class=\"pdf-description\">Delicata mousse aminoacidica 4 in 1 che rimuove il trucco, deterge, idrata e lenisce; lascia la pelle fresca ed equilibrata.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n  <!-- WELL-AGING\uff08\u65b0\u589e 3 \u6761\uff09 -->\r\n  <div class=\"pdf-box\" data-cat=\"well-aging\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/High-Concentration-HPR-Anti-Aging-Cream-L-24052102-1.pdf\" target=\"_blank\" class=\"pdf-icon\" download><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/High-Concentration-HPR-Anti-Aging-Cream-L-24052102-1.pdf\" target=\"_blank\" class=\"download-button\" download>SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Crema antiet\u00e0 HPR ad alta concentrazione<\/div>\r\n      <div class=\"pdf-code\">L-24052102<\/div>\r\n      <div class=\"pdf-description\">Una potente crema anti-et\u00e0 con HPR ad alta concentrazione per ridurre visibilmente le rughe, migliorare la compattezza e aumentare la luminosit\u00e0.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <div class=\"pdf-box\" data-cat=\"well-aging\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Hanshu-Anti-wrinkle-Essence-L-25052301-1.pdf\" target=\"_blank\" class=\"pdf-icon\" download><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Hanshu-Anti-wrinkle-Essence-L-25052301-1.pdf\" target=\"_blank\" class=\"download-button\" download>SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Essenza antirughe Hanshu<\/div>\r\n      <div class=\"pdf-code\">L-25052301<\/div>\r\n      <div class=\"pdf-description\">Essenza leggera con peptidi + HA per attenuare le linee sottili, stimolare il collagene, idratare e migliorare l'elasticit\u00e0.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <div class=\"pdf-box\" data-cat=\"well-aging\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Elm-Dew-Anti-Aging-Yellow-Rose-Moisturizing-Cream-L-24120902A-1.pdf\" target=\"_blank\" class=\"pdf-icon\" download><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Elm-Dew-Anti-Aging-Yellow-Rose-Moisturizing-Cream-L-24120902A-1.pdf\" target=\"_blank\" class=\"download-button\" download>SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Crema idratante antiet\u00e0 alla Rosa Gialla di Olmo Dew<\/div>\r\n      <div class=\"pdf-code\">L-24120902A<\/div>\r\n      <div class=\"pdf-description\">Crema idratante anti-et\u00e0 con rosa gialla, peptidi e antiossidanti. Rassoda la pelle e riduce le rughe.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <!-- REPAIRING\uff08\u65b0\u589e 2 \u6761\uff09 -->\r\n  <div class=\"pdf-box\" data-cat=\"repairing\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Caviar-Velvet-Cream-Replica-L-25031001A-1.pdf\" target=\"_blank\" class=\"pdf-icon\" download><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Caviar-Velvet-Cream-Replica-L-25031001A-1.pdf\" target=\"_blank\" class=\"download-button\" download>SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Crema di velluto al caviale (imitazione)<\/div>\r\n      <div class=\"pdf-code\">L-25031001A<\/div>\r\n      <div class=\"pdf-description\">I peptidi ed emollienti ispirati al caviale restituiscono idratazione, affinano la texture e donano una luminosit\u00e0 vellutata e giovanile.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <div class=\"pdf-box\" data-cat=\"repairing\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Yuninglan-Repairing-Soothing-Essence-Oil-L-24112603-1.pdf\" target=\"_blank\" class=\"pdf-icon\" download><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Yuninglan-Repairing-Soothing-Essence-Oil-L-24112603-1.pdf\" target=\"_blank\" class=\"download-button\" download>SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Olio d'essenza riparatore e lenitivo Yuninglan<\/div>\r\n      <div class=\"pdf-code\">L-24112603<\/div>\r\n      <div class=\"pdf-description\">I lipidi nutrienti calmano la sensibilit\u00e0, accelerano il recupero della barriera e garantiscono un'idratazione duratura.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <!-- BRIGHTENING\uff08\u65b0\u589e 2 \u6761\uff09 -->\r\n  <div class=\"pdf-box\" data-cat=\"brightening\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Deep-Spot-Lightening-Essence-OilL-23083001-1.pdf\" target=\"_blank\" class=\"pdf-icon\" download><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Deep-Spot-Lightening-Essence-OilL-23083001-1.pdf\" target=\"_blank\" class=\"download-button\" download>SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Olio d'essenza schiarente per macchie profonde<\/div>\r\n      <div class=\"pdf-code\">L-23083001<\/div>\r\n      <div class=\"pdf-description\">Potenti attivi schiarenti e oli mirano all'iperpigmentazione per un colorito uniforme e luminoso.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <div class=\"pdf-box\" data-cat=\"brightening\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Long-lasting-spot-lightening-cream-2-BRCL-23110603-1.pdf\" target=\"_blank\" class=\"pdf-icon\" download><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Long-lasting-spot-lightening-cream-2-BRCL-23110603-1.pdf\" target=\"_blank\" class=\"download-button\" download>SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Crema schiarente a lunga durata (2% BRC)<\/div>\r\n      <div class=\"pdf-code\">L-23110603<\/div>\r\n      <div class=\"pdf-description\">2% BRC attenua gradualmente le macchie scure e uniforma il tono per una chiarezza duratura.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n\r\n\r\n  <!-- EYECARE\uff08\u65b0\u589e 1 \u6761\uff09 -->\r\n  <div class=\"pdf-box\" data-cat=\"eyecare\">\r\n    <div class=\"pdf-icon-wrapper\">\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Eye-mask-cream-L-24111801-1.pdf\" target=\"_blank\" class=\"pdf-icon\" download><div class=\"bar\"><span>PDF<\/span><\/div><\/a>\r\n      <a href=\"https:\/\/www.zleygroup.com\/wp-content\/uploads\/2025\/07\/Eye-mask-cream-L-24111801-1.pdf\" target=\"_blank\" class=\"download-button\" download>SCARICA<\/a>\r\n    <\/div>\r\n    <div class=\"pdf-details\">\r\n      <div class=\"pdf-title\">Maschera per gli occhi in crema<\/div>\r\n      <div class=\"pdf-code\">L-24111801<\/div>\r\n      <div class=\"pdf-description\">L'idratazione intensa e i peptidi lenitivi riducono le borse e attenuano le rughe.<\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n<\/div>\r\n\r\n\r\n\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Home cosmetic formulation of skincare products Our formulas not only reflect the latest skincare trends, but also balance stability and [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1772","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.zleygroup.com\/it\/wp-json\/wp\/v2\/pages\/1772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zleygroup.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zleygroup.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zleygroup.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zleygroup.com\/it\/wp-json\/wp\/v2\/comments?post=1772"}],"version-history":[{"count":0,"href":"https:\/\/www.zleygroup.com\/it\/wp-json\/wp\/v2\/pages\/1772\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.zleygroup.com\/it\/wp-json\/wp\/v2\/media?parent=1772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}